{"id":673,"date":"2022-02-26T14:00:34","date_gmt":"2022-02-26T14:00:34","guid":{"rendered":"https:\/\/bizmi.in\/himenviro\/?post_type=spare-parts&#038;p=673"},"modified":"2022-03-19T03:37:18","modified_gmt":"2022-03-19T03:37:18","slug":"u-quvurli-manometr","status":"publish","type":"spare-parts","link":"https:\/\/www.intensiv-filter-himenviro.com\/uz\/ehtiyot-qismlar\/u-quvurli-manometr\/","title":{"rendered":"U-tubeli manometr"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":666,"template":"","meta":{"_acf_changed":false},"class_list":["post-673","spare-parts","type-spare-parts","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/uz\/wp-json\/wp\/v2\/spare-parts\/673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/uz\/wp-json\/wp\/v2\/spare-parts"}],"about":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/uz\/wp-json\/wp\/v2\/types\/spare-parts"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intensiv-filter-himenviro.com\/uz\/wp-json\/wp\/v2\/media\/666"}],"wp:attachment":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/uz\/wp-json\/wp\/v2\/media?parent=673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}