{"id":553,"date":"2022-02-22T15:45:39","date_gmt":"2022-02-22T15:45:39","guid":{"rendered":"https:\/\/bizmi.in\/himenviro\/?post_type=ifh_news&#038;p=553"},"modified":"2023-01-04T20:43:05","modified_gmt":"2023-01-04T20:43:05","slug":"journee-portes-ouvertes","status":"publish","type":"ifh-news","link":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/actualites-de-lifh\/journee-portes-ouvertes\/","title":{"rendered":"Journ\u00e9e portes ouvertes"},"content":{"rendered":"<p>Le 7 juin 2008, <strong>Filtre intensif himenviro<\/strong> Les visiteurs ont pu jeter un \u0153il dans les coulisses. Des visites guid\u00e9es de tous les d\u00e9partements ont permis d&#039;avoir un aper\u00e7u int\u00e9ressant. En production, il est apparu que les installations de filtrage d&#039;Intensiv-Filter n&#039;avaient rien \u00e0 voir avec les filtres \u00e0 caf\u00e9. Des machines \u00e0 commande num\u00e9rique traitent sans probl\u00e8me les plaques d&#039;acier, qui sont ensuite soud\u00e9es au bo\u00eetier des installations de filtrage. Mais les filtres ne sont pas uniquement constitu\u00e9s d&#039;acier et de t\u00f4les, des tissus sont \u00e9galement trait\u00e9s. Les supports filtrants sont fabriqu\u00e9s dans notre atelier de couture.<br \/>\nCe fut une journ\u00e9e r\u00e9ussie avec un temps magnifique et une excellente restauration pour tous les employ\u00e9s, invit\u00e9s, r\u00e9sidents et toute autre personne int\u00e9ress\u00e9e.<\/p>","protected":false},"featured_media":1981,"template":"","meta":{"_acf_changed":false},"class_list":["post-553","ifh-news","type-ifh-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/wp-json\/wp\/v2\/ifh-news\/553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/wp-json\/wp\/v2\/ifh-news"}],"about":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/wp-json\/wp\/v2\/types\/ifh-news"}],"version-history":[{"count":0,"href":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/wp-json\/wp\/v2\/ifh-news\/553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/wp-json\/wp\/v2\/media\/1981"}],"wp:attachment":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/fr\/wp-json\/wp\/v2\/media?parent=553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}