{"id":28106,"date":"2025-08-08T17:43:50","date_gmt":"2025-08-08T17:43:50","guid":{"rendered":"https:\/\/www.intensiv-filter-himenviro.com\/?post_type=job&#038;p=28106"},"modified":"2025-08-08T17:46:54","modified_gmt":"2025-08-08T17:46:54","slug":"service-inbetriebnahme-ingenieur-internationale-projekte-deutschland-frankreich","status":"publish","type":"job","link":"https:\/\/www.intensiv-filter-himenviro.com\/de\/arbeit\/service-inbetriebnahme-ingenieur-internationale-projekte-deutschland-frankreich\/","title":{"rendered":"Service- und Inbetriebnahmeingenieur \u2013 Internationale Projekte (Deutschland und Frankreich)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-28106","job","type-job","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/de\/wp-json\/wp\/v2\/job\/28106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/de\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/de\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/www.intensiv-filter-himenviro.com\/de\/wp-json\/wp\/v2\/media?parent=28106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}